{"id":24304,"date":"2026-03-13T12:55:10","date_gmt":"2026-03-13T11:55:10","guid":{"rendered":"https:\/\/colorfest.it\/?p=24304"},"modified":"2026-03-13T14:36:59","modified_gmt":"2026-03-13T13:36:59","slug":"colour-fest-2026-die-ersten-ankundigungen-des-programms-fur-die-14-ausgabe-in-lamezia-terme","status":"publish","type":"post","link":"https:\/\/colorfest.it\/de\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/","title":{"rendered":"Farbfest 2026 Anzeigen"},"content":{"rendered":"<h1 class=\"wp-block-heading\" id=\"h-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\">Erste Ank\u00fcndigungen des Programms f\u00fcr die 14. Ausgabe in Lamezia Terme<\/h1>\n\n\n\n<p><strong>Apparat, Cosmo, Django Django, The Zen Circus, La Ni\u00f1a, Tutti Fenomeni und viele mehr: Dies sind die ersten 14 K\u00fcnstler, die f\u00fcr den 11., 12. und 13. August 2026 in Riviera dei Tramonti best\u00e4tigt wurden. Das Programm wird laufend aktualisiert und es werden mehr als 20 K\u00fcnstler erwartet.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/colorfest.it\/wp-content\/uploads\/2026\/03\/Lineup-Color-Fest-14-12-Marzo-819x1024.webp\" alt=\"\" class=\"wp-image-24310\" style=\"aspect-ratio:0.799801632715343;object-fit:cover;width:368px;height:auto\" srcset=\"https:\/\/colorfest.it\/wp-content\/uploads\/2026\/03\/Lineup-Color-Fest-14-12-Marzo-819x1024.webp 819w, https:\/\/colorfest.it\/wp-content\/uploads\/2026\/03\/Lineup-Color-Fest-14-12-Marzo-240x300.webp 240w, https:\/\/colorfest.it\/wp-content\/uploads\/2026\/03\/Lineup-Color-Fest-14-12-Marzo-768x960.webp 768w, https:\/\/colorfest.it\/wp-content\/uploads\/2026\/03\/Lineup-Color-Fest-14-12-Marzo-10x12.webp 10w, https:\/\/colorfest.it\/wp-content\/uploads\/2026\/03\/Lineup-Color-Fest-14-12-Marzo.webp 1125w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Aufgebot Color Fest 14<\/figcaption><\/figure>\n\n\n\n<p>Das Color Fest kehrt zu seiner vierzehnten Ausgabe mit einem Programm zur\u00fcck, das internationale Namen und das Beste der zeitgen\u00f6ssischen italienischen Szene vereint. Drei Tage Musik am Strand Lungomare Falcone e Borsellino in Lamezia Terme, Kalabrien, vom 11. bis 13. August 2026. Der diesj\u00e4hrige Untertitel lautet <em>Sommer an einem einsamen Strand<\/em>, und bringt den Geist des Festivals perfekt auf den Punkt: Musik, Meer und der Zauber der Riviera dei Tramonti.<\/p>\n\n\n\n<p>Von den \u00fcber 20 geplanten Acts sind bereits 14 angek\u00fcndigt. Das Line-up nimmt Tag f\u00fcr Tag Gestalt an, und f\u00fcr jeden der drei Tage werden neue Namen hinzukommen. Hier ist alles, was wir bis jetzt wissen, Tag f\u00fcr Tag, mit exklusiven und einzigartigen Daten in Kalabrien.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-11-agosto-2026-day-1-apparat-per-la-prima-volta-in-calabria\">11. August 2026 - Tag 1: Apparat zum ersten Mal in Kalabrien<\/h2>\n\n\n\n<p>Der erste Tag des Color Fest 14 beginnt mit einem Namen, der allein schon die Reise wert ist: <strong>Apparat<\/strong>. Sascha Ring, einer der einflussreichsten K\u00fcnstler der globalen elektronischen Musik der letzten zwanzig Jahre, kommt zum ersten Mal \u00fcberhaupt nach Kalabrien. Sein sechstes Album, <em>Ein Brummen des Vielleicht<\/em>, erschienen im Februar 2026 bei Mute Records, sechs Jahre nach seinem Vorg\u00e4nger <em>LP5<\/em> (Grammy-nominiert), wurde von der internationalen Kritik begeistert aufgenommen. Ein Live-Set, das verspricht, eine immersive Erfahrung zwischen Elektronik und orchestralen Melodien zu sein, mit dem Meer und dem Sonnenuntergang als nat\u00fcrliche Kulisse.<\/p>\n\n\n\n<p>Neben Apparat pr\u00e4sentiert Day 1 <strong>Komm schon Tigre<\/strong>, ein Projekt, das Weltmusik, Elektronik und Jazz mit einem einzigartigen visuellen und performativen Ansatz verbindet. Um den Tag abzurunden, <strong>James Holden &amp; Wac\u0142aw Zimpel<\/strong>, eine Zusammenarbeit, bei der die kosmische Elektronik des britischen Produzenten mit der Klarinette und den Kl\u00e4ngen des polnischen K\u00fcnstlers kombiniert wird, und <strong>Gaia Banfi<\/strong>. Das Programm f\u00fcr den ersten Tag steht noch nicht fest: Weitere K\u00fcnstler werden in den kommenden Wochen bekannt gegeben.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-12-agosto-2026-day-2-cosmo-al-mattino-zen-circus-e-tutti-fenomeni-di-sera\">12. August 2026 - Tag 2: Cosmo am Morgen, Zen-Zirkus und Tutti Fenomeni am Abend<\/h2>\n\n\n\n<p>Der zweite Tag des Color Fest 14 ist der Tag mit den meisten \u00dcberraschungen, beginnend mit einem v\u00f6llig neuen Format: die <strong>Cosmo's Morgenkonzert<\/strong>, von 8.00 bis 11.00 Uhr Marco Bianchi wird sein neues Album vorstellen <em>Die Quelle<\/em>, das im April 2026 bei Columbia Records\/42Records in einer speziell f\u00fcr die Morgenstunden konzipierten Version erscheint. Nach Jahren des Experimentierens - von Cosmotrain bis zu den mehr als achtst\u00fcndigen Love Feasts - erfindet Cosmo mit seinen Matinee-Konzerten das Konzept des Live-Konzerts neu: eine Klangreise, die das Publikum vom Aufwachen bis zum Beginn des Tages begleitet, zwischen ausgedehnten Atmosph\u00e4ren und Momenten reiner Energie. Ein Erlebnis, das man mit dem Sonnenaufgang \u00fcber dem Meer der Riviera dei Tramonti erleben kann.<\/p>\n\n\n\n<p>Das Konzert am Vormittag ist in der Dauerkarte, in den Dauerkarten, die den 12. August einschlie\u00dfen, in der Tageskarte f\u00fcr den 12. August und in einer Karte, die ausschlie\u00dflich der Vormittagsveranstaltung gewidmet ist, enthalten.<\/p>\n\n\n\n<p>Am Abend des 12. August geht es weiter mit <strong>Der Zen-Zirkus<\/strong> unter <strong>einziges Date in Kalabrien<\/strong>. Appino, Ufo und Karim, die zu den repr\u00e4sentativsten Bands des italienischen Indie-Rocks geh\u00f6ren, werden ihr neues Album auf die B\u00fchne des Color Festivals bringen. <em>Das B\u00f6se<\/em>, Sie best\u00e4tigen eine Karriere, die sie zu unzertrennlichen Begleitern einer ganzen Generation gemacht hat.<\/p>\n\n\n\n<p>Immer in <strong>einziges Date in Kalabrien<\/strong>, ankommt. <strong>Alle Ph\u00e4nomene<\/strong>. Giorgio Quarzo Guarascio kehrt nach drei Jahren diskographischer Stille mit <em>Montag<\/em>, sein drittes Album, produziert von Giorgio Poi f\u00fcr 42 Records\/Epic Records Italy. Ein Album, das von Kritikern bereits zu den besten italienischen Ver\u00f6ffentlichungen des Jahres 2026 gez\u00e4hlt wird: kultiviertes Songwriting, scharfe Ironie und Pop-Melodien, die im Kopf bleiben.<\/p>\n\n\n\n<p>Das Programm von Tag 2 umfasst au\u00dferdem <strong>Y\u012bn Y\u012bn<\/strong>, das niederl\u00e4ndische Duo, das eine unwiderstehliche Mischung aus Psychedelia, Funk und s\u00fcdostasiatischen Kl\u00e4ngen auf die B\u00fchne bringt, und <strong>Nico Arezzo + Anna Castiglia<\/strong> als besonderer Gast. Anna Castiglia ist \u00fcbrigens die Gewinnerin des Targa Tenco 2025 f\u00fcr das beste Erstlingswerk mit ihrem Album <em>Mag<\/em>. Auch f\u00fcr den zweiten Tag sind weitere Ank\u00fcndigungen geplant: Das Programm steht noch nicht fest.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-13-agosto-2026-day-3-la-nina-django-django-e-il-gran-finale\">13. August 2026 - Tag 3: La Ni\u00f1a, Django Django und das gro\u00dfe Finale<\/h2>\n\n\n\n<p>Der dritte und letzte Tag des Color Fest 14 beschlie\u00dft das Festival mit einem Abend, der unvergesslich zu werden verspricht. Der Protagonist ist <strong>La Ni\u00f1a<\/strong> unter <strong>einziges Date in Kalabrien<\/strong>Carola Moccia, neapolitanische Singer-Songwriterin und Gewinnerin des Targa Tenco 2025 als bestes Album in Mundart f\u00fcr <em>Fur\u00e8sta<\/em>, La Ni\u00f1a wird ihre Show mit dem Meer, Stromboli und dem Vollmond im R\u00fccken bringen. La Ni\u00f1a, die vom Rolling Stone als eine Mischung aus Teresa De Sio und Rosal\u00eda bezeichnet wurde, hat ein Projekt geschaffen, das neapolitanische Tradition und zeitgen\u00f6ssische Kl\u00e4nge in einem Choralbum von gro\u00dfer Kraft und Wirkung vereint, das Kritiker und Publikum gleicherma\u00dfen \u00fcberzeugen kann. Ein Konzert, das an der Riviera dei Tramonti eine einzigartige und unwiederholbare Atmosph\u00e4re schaffen wird.<\/p>\n\n\n\n<p>Der internationale Abschluss des Festivals wird von der <strong>Django Django<\/strong>, das britische Quartett, das seit mehr als einem Jahrzehnt eine der originellsten Realit\u00e4ten der weltweiten Indie-Rock-Szene darstellt und in der Lage ist, Art-Rock, Electronica und Psychedelia in einem sofort erkennbaren Sound zu vereinen.<\/p>\n\n\n\n<p>An Tag 3 werden auch die <strong>Deadletter<\/strong>, ein explosives britisches Post-Punk-Kollektiv mit gro\u00dfer Live-Energie, und <strong>Mai Mai<\/strong>, ein experimentelles und industrielles Elektronikprojekt des italienischen K\u00fcnstlers Toni Cutrone, das die Klangwurzeln des Mittelmeers mit einem rituellen und hypnotischen Ansatz erforscht. Auch das Programm f\u00fcr den dritten Tag steht noch nicht fest, weitere Acts werden noch bekannt gegeben.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify-Einbettung: Farbfest 14\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/playlist\/3xk8NdbqWAlYDWwLW6iGd5?si=35963166d6f9440c&amp;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-color-fest-2026-informazioni-pratiche\">Color Fest 2026: praktische Informationen<\/h2>\n\n\n\n<p><strong>Wo:<\/strong> Lungomare Falcone e Borsellino - Riviera dei Tramonti, Lamezia Terme (CZ), Kalabrien, S\u00fcditalien<\/p>\n\n\n\n<p><strong>Wann:<\/strong> 11-12-13 August 2026<\/p>\n\n\n\n<p><strong>Tickets erh\u00e4ltlich:<\/strong> Drei-Tages-Dauerkarten, Zwei-Tages-Dauerkarten (11.\/12. August und 12.\/13. August), Tageskarten und eine spezielle Karte nur f\u00fcr das Morgenkonzert von Cosmo (12. August).<\/p>\n\n\n\n<p><strong>Wie viele K\u00fcnstler?<\/strong> Bislang wurden 14 von mehr als 20 geplanten Auftritten angek\u00fcndigt. Das Programm wird f\u00fcr alle drei Tage aktualisiert: Mit den n\u00e4chsten Ank\u00fcndigungen wird der Preis der Dauerkarten steigen.<\/p>\n\n\n\n<p><strong>Karten und Informationen:<\/strong> <a href=\"https:\/\/colorfest.it\/de\/tickets-info\/\">colourfest.de\/tickets-info\/<\/a><\/p>\n\n\n\n<p>Das Color Fest wird von der Vereinigung <em>Was sind Wolken?<\/em> APS, seit 2012 in der Kulturproduktion in Kalabrien t\u00e4tig. Seit 2013, dem Jahr der ersten Ausgabe des Festivals, hat sich das Color Fest zu einem der Bezugspunkte f\u00fcr unabh\u00e4ngige Musik in S\u00fcditalien entwickelt und K\u00fcnstler wie Franz Ferdinand, Editors, Brunori Sas, Afterhours, Marlene Kuntz, Fulminacci und viele andere auf seine B\u00fchnen gebracht.<\/p>\n\n\n\n<div class=\"wp-block-webfactory-map\"><div class=\"wp-block-webfactory-map\"><iframe title=\"Karte\" width=\"100%\" height=\"300px\" src=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?q=color%20fest&amp;maptype=roadmap&amp;zoom=10&amp;key=AIzaSyCkZ4OiAzwxwAIPSAuUNABhKJKgbafAfnY\" frameborder=\"0\"><\/iframe><\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Artikel wird aktualisiert. Folgen Sie Color Fest auf den sozialen Kan\u00e4len, um sich \u00fcber das kommende Lineup zu informieren.<\/em><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Primi annunci della lineup della 14\u00b0 edizione a Lamezia Terme Apparat, Cosmo, Django Django, The Zen Circus, La Ni\u00f1a, Tutti Fenomeni e molti altri: ecco i primi 14 artisti confermati per l&#8217;11, 12 e 13 agosto 2026 in Riviera dei Tramonti. La lineup \u00e8 in aggiornamento con oltre 20 act previsti. Il Color Fest torna [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":23610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,175,168],"tags":[],"class_list":["post-24304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-color-fest","category-color-fest-14","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Color Fest 2026 \u2014 Lineup, Date e Biglietti | 11-12-13 Agosto<\/title>\n<meta name=\"description\" content=\"Apparat, Cosmo, Zen Circus, La Ni\u00f1a, Tutti Fenomeni e altri: scopri la lineup del Color Fest il 11-12-13 agosto 2026, Lamezia Terme (CZ)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colorfest.it\/de\/colour-fest-2026-die-ersten-ankundigungen-des-programms-fur-die-14-ausgabe-in-lamezia-terme\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Color Fest 2026 Annunci\" \/>\n<meta property=\"og:description\" content=\"Color Fest - Festival di Musica, dal 2013 punto di riferimento per la musica dal vivo &gt;&gt; 11 - 12 - 13 Agosto 2026 Lungomare Falcone Borsellino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colorfest.it\/de\/colour-fest-2026-die-ersten-ankundigungen-des-programms-fur-die-14-ausgabe-in-lamezia-terme\/\" \/>\n<meta property=\"og:site_name\" content=\"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 | in Calabria\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/colorfestlamezia\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-13T11:55:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T13:36:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colorfest.it\/wp-content\/uploads\/2026\/02\/background-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salvatore Bilotti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salvatore Bilotti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/\"},\"author\":{\"name\":\"Salvatore Bilotti\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#\\\/schema\\\/person\\\/174195bbe9c056259e2ca3e13087d54b\"},\"headline\":\"Color Fest 2026 Annunci\",\"datePublished\":\"2026-03-13T11:55:10+00:00\",\"dateModified\":\"2026-03-13T13:36:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/\"},\"wordCount\":1072,\"publisher\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/background-scaled.jpg\",\"articleSection\":[\"Color Fest\",\"Color Fest 14\",\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/\",\"url\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/\",\"name\":\"Color Fest 2026 \u2014 Lineup, Date e Biglietti | 11-12-13 Agosto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/background-scaled.jpg\",\"datePublished\":\"2026-03-13T11:55:10+00:00\",\"dateModified\":\"2026-03-13T13:36:59+00:00\",\"description\":\"Apparat, Cosmo, Zen Circus, La Ni\u00f1a, Tutti Fenomeni e altri: scopri la lineup del Color Fest il 11-12-13 agosto 2026, Lamezia Terme (CZ)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/background-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/background-scaled.jpg\",\"width\":2560,\"height\":1124},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/colorfest.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Color Fest 2026 Annunci\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#website\",\"url\":\"https:\\\/\\\/colorfest.it\\\/\",\"name\":\"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 | in Calabria\",\"description\":\"Color Fest - Festival di Musica, dal 2013 punto di riferimento per la musica dal vivo &gt;&gt; 11 - 12 - 13 Agosto 2026 Lungomare Falcone Borsellino.\",\"publisher\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/#organization\"},\"alternateName\":\"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 @Lungomare Falcone Borsellino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colorfest.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#organization\",\"name\":\"Che cosa sono le nuvole APS\",\"alternateName\":\"Color Fest\",\"url\":\"https:\\\/\\\/colorfest.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/checosasonolenuvole.png\",\"contentUrl\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/checosasonolenuvole.png\",\"width\":952,\"height\":844,\"caption\":\"Che cosa sono le nuvole APS\"},\"image\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/colorfestlamezia\\\/\",\"http:\\\/\\\/instagram.com\\\/color_fest_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/color-fest\\\/\"],\"description\":\"Color Fest - Festival di Musica, dal 2013 punto di riferimento per la musica dal vivo >> 11 - 12 - 13 Agosto 2026 Lungomare Falcone Borsellino.\",\"email\":\"scrivi@colorfest.it\",\"legalName\":\"Che cosa sono le nuvole APS\",\"foundingDate\":\"2012-10-12\",\"vatID\":\"03309120792\",\"taxID\":\"92029190797\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#\\\/schema\\\/person\\\/174195bbe9c056259e2ca3e13087d54b\",\"name\":\"Salvatore Bilotti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g\",\"caption\":\"Salvatore Bilotti\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Color Fest 2026 - Lineup, Termine und Tickets | 11-12-13 August","description":"Apparat, Cosmo, Zen Circus, La Ni\u00f1a, Tutti Fenomeni und andere: Entdecken Sie das Programm des Color Fest am 11-12-13 August 2026, Lamezia Terme (CZ)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colorfest.it\/de\/colour-fest-2026-die-ersten-ankundigungen-des-programms-fur-die-14-ausgabe-in-lamezia-terme\/","og_locale":"de_DE","og_type":"article","og_title":"Color Fest 2026 Annunci","og_description":"Color Fest - Festival di Musica, dal 2013 punto di riferimento per la musica dal vivo >> 11 - 12 - 13 Agosto 2026 Lungomare Falcone Borsellino.","og_url":"https:\/\/colorfest.it\/de\/colour-fest-2026-die-ersten-ankundigungen-des-programms-fur-die-14-ausgabe-in-lamezia-terme\/","og_site_name":"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 | in Calabria","article_publisher":"http:\/\/facebook.com\/colorfestlamezia\/","article_published_time":"2026-03-13T11:55:10+00:00","article_modified_time":"2026-03-13T13:36:59+00:00","og_image":[{"width":2560,"height":1124,"url":"https:\/\/colorfest.it\/wp-content\/uploads\/2026\/02\/background-scaled.jpg","type":"image\/jpeg"}],"author":"Salvatore Bilotti","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Salvatore Bilotti","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/#article","isPartOf":{"@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/"},"author":{"name":"Salvatore Bilotti","@id":"https:\/\/colorfest.it\/#\/schema\/person\/174195bbe9c056259e2ca3e13087d54b"},"headline":"Color Fest 2026 Annunci","datePublished":"2026-03-13T11:55:10+00:00","dateModified":"2026-03-13T13:36:59+00:00","mainEntityOfPage":{"@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/"},"wordCount":1072,"publisher":{"@id":"https:\/\/colorfest.it\/#organization"},"image":{"@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/#primaryimage"},"thumbnailUrl":"https:\/\/colorfest.it\/wp-content\/uploads\/2026\/02\/background-scaled.jpg","articleSection":["Color Fest","Color Fest 14","News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/","url":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/","name":"Color Fest 2026 - Lineup, Termine und Tickets | 11-12-13 August","isPartOf":{"@id":"https:\/\/colorfest.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/#primaryimage"},"image":{"@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/#primaryimage"},"thumbnailUrl":"https:\/\/colorfest.it\/wp-content\/uploads\/2026\/02\/background-scaled.jpg","datePublished":"2026-03-13T11:55:10+00:00","dateModified":"2026-03-13T13:36:59+00:00","description":"Apparat, Cosmo, Zen Circus, La Ni\u00f1a, Tutti Fenomeni und andere: Entdecken Sie das Programm des Color Fest am 11-12-13 August 2026, Lamezia Terme (CZ)","breadcrumb":{"@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/#primaryimage","url":"https:\/\/colorfest.it\/wp-content\/uploads\/2026\/02\/background-scaled.jpg","contentUrl":"https:\/\/colorfest.it\/wp-content\/uploads\/2026\/02\/background-scaled.jpg","width":2560,"height":1124},{"@type":"BreadcrumbList","@id":"https:\/\/colorfest.it\/color-fest-2026-i-primi-annunci-della-lineup-della-14-edizione-a-lamezia-terme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/colorfest.it\/"},{"@type":"ListItem","position":2,"name":"Color Fest 2026 Annunci"}]},{"@type":"WebSite","@id":"https:\/\/colorfest.it\/#website","url":"https:\/\/colorfest.it\/","name":"Color Fest - Musikfestival | 11 - 12 - 13 August 2026 | in Kalabrien","description":"Color Fest - Musikfestival, seit 2013 ein Bezugspunkt f\u00fcr Live-Musik &gt;&gt; 11 - 12 - 13 August 2026 Lungomare Falcone Borsellino","publisher":{"@id":"https:\/\/colorfest.it\/#organization"},"alternateName":"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 @Lungomare Falcone Borsellino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colorfest.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/colorfest.it\/#organization","name":"Was sind APS-Wolken?","alternateName":"Color Fest","url":"https:\/\/colorfest.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colorfest.it\/#\/schema\/logo\/image\/","url":"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/03\/checosasonolenuvole.png","contentUrl":"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/03\/checosasonolenuvole.png","width":952,"height":844,"caption":"Che cosa sono le nuvole APS"},"image":{"@id":"https:\/\/colorfest.it\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/colorfestlamezia\/","http:\/\/instagram.com\/color_fest_\/","https:\/\/www.linkedin.com\/company\/color-fest\/"],"description":"Color Fest - Musikfestival, seit 2013 ein Bezugspunkt f\u00fcr Live-Musik &gt;&gt; 11 - 12 - 13 August 2026 Lungomare Falcone Borsellino","email":"scrivi@colorfest.it","legalName":"Che cosa sono le nuvole APS","foundingDate":"2012-10-12","vatID":"03309120792","taxID":"92029190797","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/colorfest.it\/#\/schema\/person\/174195bbe9c056259e2ca3e13087d54b","name":"Salvatore Bilotti","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g","caption":"Salvatore Bilotti"}}]}},"_links":{"self":[{"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/posts\/24304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/comments?post=24304"}],"version-history":[{"count":0,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/posts\/24304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/media\/23610"}],"wp:attachment":[{"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/media?parent=24304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/categories?post=24304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/tags?post=24304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}