{"id":11317,"date":"2022-12-30T15:42:01","date_gmt":"2022-12-30T14:42:01","guid":{"rendered":"https:\/\/colorfest.it\/?p=11317"},"modified":"2024-01-19T11:18:37","modified_gmt":"2024-01-19T10:18:37","slug":"backstage","status":"publish","type":"post","link":"https:\/\/colorfest.it\/de\/backstage\/","title":{"rendered":"Farbfest Backstage"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11317\" class=\"elementor elementor-11317\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db4152a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db4152a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78cc2b2\" data-id=\"78cc2b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6b144d elementor-widget elementor-widget-heading\" data-id=\"c6b144d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PODCAST<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09919fe elementor-widget elementor-widget-text-editor\" data-id=\"09919fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>\n<h2><span style=\"font-family: mazius;\">Color Fest Backstage<\/span><\/h2>\n<\/div>\n<h6>Di Color Fest<\/h6>\n<div>\n<div>\n<div>\n<div>\n<p>Color Fest Backstage &#8211; 10 anni di Festival<\/p>\n<p>Nelle tre giornate del Color Fest abbiamo registrato un Podcast condotto da <strong><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"https:\/\/www.linkedin.com\/in\/vittorio-ondedei-b016b95b\/?originalSubdomain=it\">Vittorio Ondedei<\/a><\/span> <\/strong>(<span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"https:\/\/it.wikipedia.org\/wiki\/I_Camillas\">Camillas<\/a><\/span>) e <strong><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"https:\/\/www.instagram.com\/eclissidistorta\/?hl=it\">Sara Di Iacovo<\/a><\/span><\/strong>, fatto di interviste e racconti della decima edizione con storie di <span style=\"text-decoration: underline;\">#Backstage<\/span> delle 9 edizioni precedenti e perch\u00e9 no di interviste fatte al pubblico del festival.<\/p>\n<p>Nel Podcast parleremo con N.A.I.P., Naska, Nu Genea, Ginevra, Marco Castello, Emma Nolde, Savana Funk, MACE e tanti altri&#8230;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abbb77f elementor-widget elementor-widget-accordion\" data-id=\"abbb77f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1801\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1801\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Podcast 2022<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1801\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1801\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1802\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1802\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">N.A.I.P.<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1802\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1802\"><h4>N.A.I.P. in Calabria al Color Fest 10<\/h4><p>N.A.I.P. torna in Calabria ! L\u2019artista rivelazione di X Factor 2020,\u00a0<strong>N.A.I.P, arriva al Color Fest 10 l\u201911 Agosto 2022 con il \u201cDOVREI ESSERE IN TOUR \u201c<\/strong>la sua nuova avventura dal vivo.<\/p><p>N.A.I.P. \u00e8 l\u2019acronimo di \u201cNessun artista in particolare\u201d, il progetto musicale di cantautorato elettronico alternativo di Michelangelo Mercuri: un\u2019operazione delicata, rischiosa, audace; una grande capacit\u00e0 performativa al servizio di una scrittura innovativa, fortemente identitaria e scevra di etichette musicali.<\/p><p>Il suo nome \u00e8 un manifesto di intenti, una proposta provocatoria e disturbante, ma fortemente radicata con la narrazione del cantautorato italiano dell\u2019et\u00e0 dell\u2019oro.<\/p><p>Octapad, synth, chitarra e voce sono gli strumenti che entrano in un vortice di ripetizioni generate da una loop station, cos\u00ec i mantra di \u201cBravi nel Breve\u201d, di \u201cOh Oh Oh\u201d, di \u201cPartecipo\u201d prendono vita, diventando brani ipnotici che dopo ogni ascolto si fissano in testa: su tutti il singolo \u201cAttenti al Loop\u201d.<\/p><p>Finalista a X Factor 2020, il suo percorso \u2013 all\u2019interno del format televisivo \u2013 \u00e8 stato all\u2019insegna della sperimentazione sonora, di un\u2019innata capacit\u00e0 creativa, che gli ha permesso di sviluppare un viaggio musicale profondamente contemporaneo e multiforme.<\/p><div><strong>N.A.I.P. \u2013 11 Agosto 2022<\/strong><\/div><div><strong>Color Fest 10 \u2013 This Must Be The Place<\/strong><br \/><strong>Agriturismo Costantino<\/strong><\/div><div>\u00a0<\/div><div><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"#podcast\"><strong>Ti sei perso il Color Fest ? ascolta qui il PODCAST!<\/strong><\/a><\/span><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1803\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1803\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">NASKA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1803\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1803\"><h4>Naska\u00a0<span class=\"_7UhW9 xLCgt MMzan KV-D4 se6yk T0kll \">in Calabria al Color Fest 10<\/span><\/h4><p>E\u2019 tornato il punk rock. Noi ce lo facciamo raccontare da Naska in Calabria sul palco del Color Fest 10.<\/p><p>Naska nome d\u2019arte di Diego Caterbetti, nasce nel 1997 a Civitanova Marche.<\/p><p>Finito il liceo si trasferisce a Milano, per concentrarsi sul suo percorso musicale. Cresciuto con la scena punk\/rock di blink 182 e Sum 41, in seguito si appassiona alla scena emo trap americana rappresentata da Lil Peep: influenze che trovano ampio spazio nella sua musica e che gli consentono di dare al suo progetto un sound al momento unico in Italia. Nel 2020 pubblica il suo primo EP \u201cALO\/VE\u201d, per Sony Music.<\/p><p>Il primo singolo estratto \u00e8 \u201cDormi\u201d, manifesto della gelosia, dell\u2019insicurezza e della fiducia nelle relazioni dei ragazzi di oggi. Pubblica di seguito \u201cTu che ne sai\u201d, \u201cCalifornia\u201d, \u201cMamma non mi parla\u201d e \u201cSpezzami il cuore\u201d, singoli che precedono il suo prossimo progetto discografico. Oltre alla musica, nel 2019 apre il suo canale Twitch e inizia il suo percorso parallelo da streamer, raggiungendo un fidelizzato pubblico che lo segue nelle trasmissioni quotidiane. \u201cRebel\u201d \u00e8 il suo disco d\u2019esordio ufficiale.<\/p><div>\u00a0<\/div><div><strong>Naska \u2013 11 Agosto<\/strong><br \/><strong>Color Fest 10 \u2013 This Must Be The Place<\/strong><br \/><strong>Agriturismo Costantino<\/strong><\/div><div>\u00a0<\/div><div style=\"text-align: center;\"><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"#podcast\"><strong>Ti sei perso il Color Fest ? ascolta qui il PODCAST!<\/strong><\/a><\/span><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1804\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1804\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Nu Genea<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1804\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1804\"><h4>Nu Gena\u00a0<span class=\"_7UhW9 xLCgt MMzan KV-D4 se6yk T0kll \">in Calabria al Color Fest 10<\/span><\/h4><p>Il duo\u00a0<strong><a href=\"https:\/\/it.wikipedia.org\/wiki\/Nu_Genea\">Nu Guinea<\/a><\/strong>, formatosi a Napoli e ora di stanza a Berlino, crea delle sonorit\u00e0 influenzate dall\u2019idea di un luogo esotico, forse immaginario, frutto di una costante ricerca musicale nel passato. Il loro percorso pu\u00f2 essere definito come un\u2019indagine storica sulla musica da \u201cdancefloor\u201dnel suo senso pi\u00f9 puro. La chiave \u00e8 la contaminazione fra generi\u00a0musicali nata dall\u2019incontro fra differenti culture e popolazioni.<\/p><p>Il progetto nasce dall\u2019idea di jam sessions, fusioni fra sintetizzatori elettronici e strumenti tradizionali, caratterizzato da un suono che non mira alla perfezione, ma alla \u201cgenuinit\u00e0\u201d e che pu\u00f2 essere inteso come una forma in costante mutamento. Il primo lavoro pubblicato su Early Sounds Recordings nel 2014 \u00e8 seguito dal disco \u201cWorld Ep\u201d su Tartelet Records. Nel 2016 esce The Tony Allen Experiments, con la collaborazione di Tony Allen, capostipite dell\u2019Afrobeat e batterista storico del leggendario Fela Kuti. A seguire, i Nu Guinea fondano la propria piattaforma discografica:\u00a0<a href=\"https:\/\/www.discogs.com\/it\/label\/1311746-NG-Records-5\">NG records<\/a>. La prima uscita \u00e8 un 45 giri dal titolo Amore, cover di un brano italiano della fine degli anni \u201970. Il 2018 segna invece un ritorno alle origini. Nuova Napoli , questo il titolo dell\u2019ultimo LP, rappresenta un focus speciale sulla citt\u00e0 natale del duo. Guardano la citt\u00e0 da lontano ricostruendo la sua energia dal loro studio di Berlino, calibrando i synth sul meridiano del Vesuvio, il vulcano che da sempre protegge\u00a0e minaccia Napoli. In questo disco i Nu Guinea si lasciano ispirare dalla musica Disco, Jazz-Funk e Fusion Napoletana, unendo tali influenze al caratteristico suono che li contraddistingue.<\/p><p><strong>Nu Genea \u2013 13 Agosto<\/strong><br \/><strong>Color Fest 10 \u2013 This Must Be The Place<\/strong><br \/><strong>Agriturismo Costantino<\/strong><\/p><p style=\"text-align: center;\"><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"#podcast\"><strong>Ti sei perso il Color Fest ? ascolta qui il PODCAST!<\/strong><\/a><\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1805\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1805\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ginevra<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1805\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1805\"><h4>Ginevra\u00a0<span class=\"_7UhW9 xLCgt MMzan KV-D4 se6yk T0kll \">in Calabria al Color Fest 10<\/span><\/h4><p>Ginevra<span class=\"_7UhW9 xLCgt MMzan KV-D4 se6yk T0kll \">\u00a0\u00e8 la nuova voce dell\u2019avant-pop italiano. Tanto raffinata quanto potente nei live.\u00a0<\/span><\/p><p>Cresciuta tra Collegno, Grugliasco e Torino, dopo essersi trasferita a\u00a0<a title=\"Milano\" href=\"https:\/\/it.wikipedia.org\/wiki\/Milano\">Milano<\/a>\u00a0nel 2012 si \u00e8 diplomata in canto al\u00a0<a title=\"Centro Professione Musica\" href=\"https:\/\/it.wikipedia.org\/wiki\/Centro_Professione_Musica\">CPM Music Institute<\/a>\u00a0per poi laurearsi in Scienze politiche all\u2019<a title=\"Universit\u00e0 degli Studi di Milano\" href=\"https:\/\/it.wikipedia.org\/wiki\/Universit%C3%A0_degli_Studi_di_Milano\">Universit\u00e0 Statale<\/a>.<sup id=\"cite_ref-1\" class=\"reference\"><\/sup><\/p><p>Fa il suo esordio nel marzo 2019 con l\u2019EP\u00a0<i><a class=\"new\" title=\"Ruins (Ginevra) (la pagina non esiste)\" href=\"https:\/\/it.wikipedia.org\/w\/index.php?title=Ruins_(Ginevra)&amp;action=edit&amp;redlink=1\">Ruins<\/a><\/i>, prodotto dal compositore e produttore milanese Francesco Fugazza. Nel mese di maggio partecipa alla decima edizione del concorso\u00a0<a title=\"Musica da bere\" href=\"https:\/\/it.wikipedia.org\/wiki\/Musica_da_bere\">Musica da Bere<\/a>, dove riceve la\u00a0<i>menzione speciale KeepOn Live<\/i><sup id=\"cite_ref-2\" class=\"reference\"><\/sup>\u00a0che la porta a settembre a suonare per la prima volta a\u00a0<a title=\"Roma\" href=\"https:\/\/it.wikipedia.org\/wiki\/Roma\">Roma<\/a>\u00a0nell\u2019ambito della manifestazione\u00a0<i>\u2018Na cosetta estiva<\/i>.<sup id=\"cite_ref-3\" class=\"reference\"><\/sup><\/p><p>il 26 Giugno 2020 esce il secondo EP\u00a0<i><a class=\"new\" title=\"Metropoli (EP) (la pagina non esiste)\" href=\"https:\/\/it.wikipedia.org\/w\/index.php?title=Metropoli_(EP)&amp;action=edit&amp;redlink=1\">Metropoli<\/a><\/i>, dove la cantautrice torinese canta in italiano. A settembre all\u2019<a title=\"Arena di Verona\" href=\"https:\/\/it.wikipedia.org\/wiki\/Arena_di_Verona\">Arena di Verona<\/a>\u00a0partecipa in duetto con\u00a0<a title=\"Ghemon\" href=\"https:\/\/it.wikipedia.org\/wiki\/Ghemon\">Ghemon<\/a>\u00a0insieme ad altri artisti al concerto evento\u00a0<i>Heroes<\/i>\u00a0trasmesso in streaming.<sup id=\"cite_ref-4\" class=\"reference\"><a href=\"https:\/\/it.wikipedia.org\/wiki\/Ginevra_(cantante)#cite_note-4\">[4]<\/a><\/sup>\u00a0Nell\u2019ottobre dello stesso anno \u00e8 stata selezionata tra i 20 semifinalisti di\u00a0<a title=\"Sanremo Giovani 2020\" href=\"https:\/\/it.wikipedia.org\/wiki\/Sanremo_Giovani_2020\">Sanremo Giovani 2020<\/a>\u00a0con il brano\u00a0<i>Vortice<\/i>.<sup id=\"cite_ref-5\" class=\"reference\"><\/sup><\/p><p>Insieme a\u00a0<a title=\"Mecna\" href=\"https:\/\/it.wikipedia.org\/wiki\/Mecna\">Mecna<\/a>\u00a0compone il brano\u00a0<i><a title=\"Soli (Mecna)\" href=\"https:\/\/it.wikipedia.org\/wiki\/Soli_(Mecna)\">Soli<\/a><\/i>, pubblicato come singolo l\u201911 febbraio 2021, che vede la partecipazione vocale della stessa Ginevra e di\u00a0<a title=\"Ghemon\" href=\"https:\/\/it.wikipedia.org\/wiki\/Ghemon\">Ghemon<\/a>\u00a0e ha come tema centrale il rapporto con la solitudine.<sup id=\"cite_ref-6\" class=\"reference\"><a href=\"https:\/\/it.wikipedia.org\/wiki\/Ginevra_(cantante)#cite_note-6\">[6]<\/a><\/sup>\u00a0Scrive il brano\u00a0<i><a title=\"Glicine (singolo)\" href=\"https:\/\/it.wikipedia.org\/wiki\/Glicine_(singolo)\">Glicine<\/a><\/i>\u00a0con cui\u00a0<a title=\"Noemi (cantante)\" href=\"https:\/\/it.wikipedia.org\/wiki\/Noemi_(cantante)\">Noemi<\/a>\u00a0partecipa al\u00a0<a title=\"Festival di Sanremo 2021\" href=\"https:\/\/it.wikipedia.org\/wiki\/Festival_di_Sanremo_2021\">Festival di Sanremo 2021<\/a>\u00a0ed \u00e8 autrice anche di alcuni brani dell\u2019album\u00a0<i><a title=\"Metamorfosi (Noemi)\" href=\"https:\/\/it.wikipedia.org\/wiki\/Metamorfosi_(Noemi)\">Metamorfosi<\/a><\/i>\u00a0della cantautrice romana. Nello stesso anno partecipa al\u00a0<a title=\"Concerto del Primo Maggio\" href=\"https:\/\/it.wikipedia.org\/wiki\/Concerto_del_Primo_Maggio\">concerto del Primo Maggio<\/a>\u00a0a Roma.<sup id=\"cite_ref-7\" class=\"reference\"><\/sup>\u00a0L\u2019estate 2021 la vede calcare i palchi del\u00a0<a title=\"MI AMI Festival\" href=\"https:\/\/it.wikipedia.org\/wiki\/MI_AMI_Festival\">MI AMI Festival<\/a>, del\u00a0<a class=\"new\" title=\"Linecheck Festival (la pagina non esiste)\" href=\"https:\/\/it.wikipedia.org\/w\/index.php?title=Linecheck_Festival&amp;action=edit&amp;redlink=1\">Linecheck Festival<\/a>\u00a0e del\u00a0<a class=\"new\" title=\"Liverpool Sound City (la pagina non esiste)\" href=\"https:\/\/it.wikipedia.org\/w\/index.php?title=Liverpool_Sound_City&amp;action=edit&amp;redlink=1\">Liverpool Sound City<\/a>.<\/p><p>Al\u00a0<a title=\"Festival di Sanremo 2022\" href=\"https:\/\/it.wikipedia.org\/wiki\/Festival_di_Sanremo_2022\">Festival di Sanremo 2022<\/a>, nella serata delle cover, Ginevra duetta con\u00a0<a title=\"La Rappresentante di Lista\" href=\"https:\/\/it.wikipedia.org\/wiki\/La_Rappresentante_di_Lista\">La Rappresentante di Lista<\/a>,\u00a0<a title=\"Cosmo (cantante)\" href=\"https:\/\/it.wikipedia.org\/wiki\/Cosmo_(cantante)\">Cosmo<\/a>\u00a0e\u00a0<a title=\"Margherita Vicario\" href=\"https:\/\/it.wikipedia.org\/wiki\/Margherita_Vicario\">Margherita Vicario<\/a>\u00a0in una\u00a0<a title=\"Cover\" href=\"https:\/\/it.wikipedia.org\/wiki\/Cover\">cover<\/a>\u00a0di\u00a0<i><a title=\"Be My Baby\" href=\"https:\/\/it.wikipedia.org\/wiki\/Be_My_Baby\">Be My Baby<\/a><\/i>\u00a0delle\u00a0<a title=\"The Ronettes\" href=\"https:\/\/it.wikipedia.org\/wiki\/The_Ronettes\">Ronettes<\/a>.<\/p><div>\u00a0<\/div><div><strong>Ginevra \u2013 13 Agosto<\/strong><br \/><strong>Color Fest 10 \u2013 This Must Be The Place<\/strong><br \/><strong>Agriturismo Costantino<\/strong><\/div><div>\u00a0<\/div><div style=\"text-align: center;\"><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"#podcast\"><strong>Ti sei perso il Color Fest ? ascolta qui il PODCAST!<\/strong><\/a><\/span><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1806\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1806\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Marco Castello<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1806\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1806\"><h4>Marco Castello\u00a0<span class=\"_7UhW9 xLCgt MMzan KV-D4 se6yk T0kll \">in Calabria al Color Fest 10<\/span><\/h4><p>Mescolate il Jazz, la disco della Motown, il Mediterraneo, e fateli parlare di amori liceali, di ormoni estivi e di vicoli di Ortigia. Con Marco Castello in Calabria, sar\u00e0 una festa romantica al Color Fest 10.<\/p><p>Marco Castello, classe 1993\u00a0\u00e8\u00a0un polistrumentista siciliano.\u00a0\u00c8 laureato ai civici corsi di jazz della scuola Claudio Abbado di Milano.\u00a0 \u00c8 in grado di suonare la batteria come un batterista funk e al tempo stesso di cantare, ma \u00e8 un drago anche alla chitarra, alla tromba, al piano e soprattutto sa scrivere canzoni. Canzoni delicate ben suonate ma pure ancorate alla contemporaneit\u00e0.<\/p><p>Dopo avervi trasportato tra i banchi di scuola con\u00a0<i>Por<\/i><i>si<\/i>, fatto ballare con\u00a0<i>Torp<\/i><i>i<\/i><i>,<\/i>\u00a0cucinato cose \u201cciccione\u201d per calmare i bisogni del corpo e della mente con\u00a0<i>Cicciona<\/i>\u00a0e rilasciato un po\u2019 di\u00a0<i>Dopamina<\/i><i>,<\/i>\u00a0esce\u00a0 per 42 Records in Italia e Bubbles Records nel resto d\u2019Europa,\u00a0<i>Contenta Tu<\/i>, l\u2019atteso disco d\u2019esordio di uno dei talenti musicali italiani pi\u00f9 originali e internazionali in circolazione: Marco Castello.\u00a0<i>Contenta tu<\/i>\u00a0\u00e8 stato registrato al\u00a0Butterama Studio di Berlino e prodotto insieme a Marcin \u00d6z (The Whitest Boy Alive) e\u00a0 al produttore e compositore Daniel Nentwig.<\/p><p>Un mix irresistibile di pop, funk,\u00a0 jazz e blues,\u00a0melodie sbarazzine e orecchiabili dal groove trascinante che fa battere il piedino e\u00a0 canzoni intime e delicate capaci di trasportarti altrove:\u00a0<i>Contenta tu\u00a0<\/i>affianca con sapienza canzoni eterogenee e imperniate di tante piccole trame dove batteria chitarre, fiati, tastiere e synth creano soluzioni armoniche sempre diverse dando vita a un sound fresco e leggero, elegante e al tempo stesso grezzo.<\/p><p>Un tuffo nei ricordi tra gite scolastiche,\u00a0 corse in motorino, jam session, primi baci e notti in spiaggia a guardare le stelle.<\/p><p>Un racconto degli anni trascorsi da Marco nella sua citt\u00e0, Siracusa , dopo aver\u00a0 studiato a Milano, girato il mondo a fianco di\u00a0Erlend \u00d8ye dei Kings of Convenience\u00a0nel progetto\u00a0La Comitiva, e avervi fatto ritorno.<\/p><p>Un vero e proprio ritorno alle origini in cui Marco \u00e8 capace di cercare (e trovare) la poesia nel grottesco, mettendo insieme alcune delle contraddizioni della societ\u00e0 contemporanea, a partire da quelle della propria citt\u00e0.<\/p><p>Al momento \u00e8 al lavoro sulla scrittura del suo secondo album, ma nei prossimi mesi sono previste altre sorprese.<\/p><div>\u00a0<\/div><div><strong>Marco Castello \u2013 13 Agosto<\/strong><br \/><strong>Color Fest 10 \u2013 This Must Be The Place<\/strong><br \/><strong>Agriturismo Costantino<\/strong><\/div><div>\u00a0<\/div><div style=\"text-align: center;\"><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"#podcast\"><strong>Ti sei perso il Color Fest ? ascolta qui il PODCAST!<\/strong><\/a><\/span><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1807\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1807\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Emma Nolde<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1807\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1807\"><h4><strong>Emma Nolde\u00a0<span class=\"_7UhW9 xLCgt MMzan KV-D4 se6yk T0kll \">in Calabria al Color Fest 10<\/span><\/strong><\/h4><p><strong>Emma Nolde<\/strong>\u00a0nasce in Toscana nell\u2019anno 2000. All\u2019et\u00e0 di quindici anni inizia a scrivere brani originali in inglese ai quali lavora senza pubblicare\u00a0alcun progetto. Poco tempo dopo comincia a lavorare a brani in italiano ed in particolare nell\u2019ultimo anno si\u00a0dedica alla realizzazione del suo primo vero progetto prodotto insieme a Renato D\u2019Amico ed\u00a0Andrea Pachetti, che sar\u00e0 pubblicato nel 2020, composto da otto brani interamente in italiano.<\/p><p>Il suo disco d\u2019esordio si chiama\u00a0<a href=\"https:\/\/www.rockit.it\/emmanolde\">Toccaterra<\/a>\u00a0ed \u00e8 uscito il 4 settembre 2020 per\u00a0<a href=\"https:\/\/www.woodworm-music.com\/\">Woodworm<\/a>\/<a href=\"https:\/\/www.polydor.co.uk\/\">Polydor<\/a>. \u00c8 stato acclamato dalla critica come un esordio veramente sorprendente ed\u00a0importante. Emma \u00e8 senza ombra di dubbio una delle voci del futuro della musica italiana.\u00a0Toccattera \u00e8 arrivato finalista al\u00a0<a href=\"https:\/\/clubtenco.it\/\">Premio Tenco<\/a>\u00a0nella sezione Opera Prima.<\/p><p><strong>EMMA NOLDE\u00a0\u2013 12 Agosto 2022<\/strong><br \/><strong>Color Fest 10 \u2013 This Must Be The Place<\/strong><br \/><strong>Agriturismo Costantino<\/strong><\/p><div style=\"text-align: center;\"><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"#podcast\"><strong>Ti sei perso il Color Fest ? ascolta qui il PODCAST!<\/strong><\/a><\/span><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1808\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1808\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Savana Funk<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1808\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1808\"><h4>Savana Funk\u00a0<span class=\"_7UhW9 xLCgt MMzan KV-D4 se6yk T0kll \">in Calabria al Color Fest 10<\/span><\/h4><p>Un trio di virtuosi che raccoglie influenze dal jazz al bacino del mediterraneo, passando per l\u2019Oriente. La loro musica \u00e8 un inno alla mescolanza tra le culture e ascoltarli dal vivo \u00e8 un viaggio al quale non puoi rinunciare.<\/p><p>I Savana Funk incarnano l\u2019essenza della live band unendo funk, rock e blues con jam incendiarie, groove irresistibili ed una presenza scenica invidiabile. Con un pubblico affezionato in rapida crescita e un crescente numero di concerti in tutta Europa hanno un nuovo, atteso album in arrivo nella primavera del 2021.<\/p><p>Aldo, Blake e Youssef si incontrano nella primavera 2015 a Bologna, scatta immediata una rara sintonia umana e musicale. Immediatamente i tre decidono di formare una band e iniziano da subito a fare molto live, a sperimentare idee e a scrivere musica.<br \/>Il primo album e\u0300 un\u2019 autoproduzione, \u201cMUSICA ANALOGA\u201d , ed esce a nome Aldo Betto w\/ Blake Franchetto &amp; Youssef Ait Bouazza nel 2016. A febbraio 2017 esce il secondo disco \u201cSAVANA FUNK\u201d (Brutture Moderne\/ Audioglobe), sempre a nome Aldo Betto w\/ Blake Franchetto &amp; Youssef Ait Bouazza. L\u2019album ottiene decine di recensioni sulle principali riviste e blog, non solo di settore. Scritto e concepito in trio, l\u2019album testimonia il processo di maturazione della band bolognese. Ad inizio 2018 il trio prende definitivamente il nome SAVANA FUNK.<\/p><p>A settembre 2018 e\u0300 uscito il terzo album, \u201cBring in the New\u201d (Brutture Moderne \/ Audioglobe). Si consolida la collaborazione con Nicola Peruch, presente fin dal primo album come musicista, ora anche co-produttore e co-autore. Nicola entra anche in pianta stabile nell\u2019organico live dei SAVANA FUNK. La maggior interazione con Peruch espande le possibilita\u0300 del gruppo, che si proietta verso nuove sonorita\u0300. A Bring in the New hanno partecipato anche Chris Costa, Don Antonio e Danilo Mineo.<br \/>Questo terzo lavoro dei Savana Funk ottiene moltissime recensioni, ottimi i responsi della critica e del pubblico.<br \/>La band continua in un\u2019attivita\u0300 live instancabile, partecipando a decine di importanti festival e rassegne. Il palco e\u0300 la dimensione congeniale per apprezzare lo spirito del gruppo. Nell\u2019estate del 2019 i Savana Funk vengono invitati a diversi appuntamenti del Jova Beach Party, i concerti estivi di Jovanotti: suonano davanti a decine di migliaia di persone, facendo anche delle lunghe jam session sul palco con Lorenzo. Nello stesso anno sono ospiti a Propaganda Live, il seguitissimo programma su La7.<br \/>Nel 2020 la band lavora ad un nuovo album in uscita a primavera 2021 con Garrincha GoGo neonata label world\/funk del gruppo Garrincha.<\/p><div>\u00a0<\/div><div><strong>Savana Funk \u2013 12 Agosto 2022<\/strong><br \/><strong>Color Fest 10 \u2013 This Must Be The Place<\/strong><br \/><strong>Agriturismo Costantino<\/strong><\/div><div>\u00a0<\/div><div style=\"text-align: center;\"><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"#podcast\"><strong>Ti sei perso il Color Fest ? ascolta qui il PODCAST!<\/strong><\/a><\/span><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1809\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1809\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">MACE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1809\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1809\"><h4><strong>MACE in Calabria al Color Fest 10<\/strong><\/h4><p>MACE in Calabria, arriva un artista che non ha bisogno di presentazioni perch\u00e9 nel caso di Mace sono le sue produzioni a parlare.<\/p><p>Mace arriva sul palco del Color Fest il 12 agosto. Pronti per ballare?<\/p><p><b>Mace<\/b>, pseudonimo di\u00a0<b>Simone Benussi<\/b>\u00a0(<a title=\"Milano\" href=\"https:\/\/it.wikipedia.org\/wiki\/Milano\">Milano<\/a>,\u00a0<a title=\"9 luglio\" href=\"https:\/\/it.wikipedia.org\/wiki\/9_luglio\">9 luglio<\/a>\u00a0<a title=\"1982\" href=\"https:\/\/it.wikipedia.org\/wiki\/1982\">1982<\/a>), \u00e8 un\u00a0<a title=\"Disc jockey\" href=\"https:\/\/it.wikipedia.org\/wiki\/Disc_jockey\">disc jockey<\/a>,\u00a0<a class=\"mw-redirect\" title=\"Beatmaker\" href=\"https:\/\/it.wikipedia.org\/wiki\/Beatmaker\">beatmaker<\/a>\u00a0e\u00a0<a title=\"Produttore discografico\" href=\"https:\/\/it.wikipedia.org\/wiki\/Produttore_discografico\">produttore discografico<\/a>\u00a0<a title=\"Italia\" href=\"https:\/\/it.wikipedia.org\/wiki\/Italia\">italiano<\/a>.<\/p><p>Ha prodotto brani per una grande variet\u00e0 di artisti, tra i quali\u00a0<a title=\"Fabri Fibra\" href=\"https:\/\/it.wikipedia.org\/wiki\/Fabri_Fibra\">Fabri Fibra<\/a>,\u00a0<a title=\"Gu\u00e9 Pequeno\" href=\"https:\/\/it.wikipedia.org\/wiki\/Gu%C3%A9_Pequeno\">Gu\u00e9 Pequeno<\/a>,\u00a0<a title=\"Marracash\" href=\"https:\/\/it.wikipedia.org\/wiki\/Marracash\">Marracash<\/a>,\u00a0<a title=\"Izi (rapper)\" href=\"https:\/\/it.wikipedia.org\/wiki\/Izi_(rapper)\">Izi<\/a>,\u00a0<a title=\"Noyz Narcos\" href=\"https:\/\/it.wikipedia.org\/wiki\/Noyz_Narcos\">Noyz Narcos<\/a>,\u00a0<a title=\"Salmo (rapper)\" href=\"https:\/\/it.wikipedia.org\/wiki\/Salmo_(rapper)\">Salmo<\/a>,\u00a0<a title=\"Lorenzo Fragola\" href=\"https:\/\/it.wikipedia.org\/wiki\/Lorenzo_Fragola\">Lorenzo Fragola<\/a>,\u00a0<a title=\"Joan Thiele\" href=\"https:\/\/it.wikipedia.org\/wiki\/Joan_Thiele\">Joan Thiele<\/a>,\u00a0<a title=\"Kaos (rapper)\" href=\"https:\/\/it.wikipedia.org\/wiki\/Kaos_(rapper)\">Kaos<\/a>,\u00a0<a title=\"Colle der Fomento\" href=\"https:\/\/it.wikipedia.org\/wiki\/Colle_der_Fomento\">Colle der Fomento<\/a>,\u00a0<a title=\"Jack the Smoker\" href=\"https:\/\/it.wikipedia.org\/wiki\/Jack_the_Smoker\">Jack the Smoker<\/a>,\u00a0<a title=\"Gemitaiz\" href=\"https:\/\/it.wikipedia.org\/wiki\/Gemitaiz\">Gemitaiz<\/a>,\u00a0<a title=\"Venerus\" href=\"https:\/\/it.wikipedia.org\/wiki\/Venerus\">Venerus<\/a>\u00a0e\u00a0<a title=\"Rkomi\" href=\"https:\/\/it.wikipedia.org\/wiki\/Rkomi\">Rkomi<\/a>.<\/p><p>\u00a0<\/p><h6><strong>Primi anni<\/strong><\/h6><p>Mace entra nel mondo dell\u2019hip hop sin dalla giovane et\u00e0, appassionandosi inizialmente al writing e in seguito alla produzione di basi musicali. Dopo un periodo di gavetta stringe un sodalizio con l\u2019MC milanese Jack the Smoker, dando vita al gruppo La Cr\u00e8me, il quale pubblica l\u2019album L\u2019alba nel 2003 attraverso la Vibrarecords. Il duo inizia a suonare in tutta Italia, con qualche comparsa anche in Svizzera, fino ad aprire il concerto di Ghostface Killah del Wu-Tang Clan al Rolling Stone di Milano.<\/p><p>Dopo il suo esordio inizia una lunga serie di collaborazioni con artisti di spicco dell\u2019hip hop italiano, producendo brani per Kaos, Colle der Fomento, Mondo Marcio, Bassi Maestro, Clementino, DJ Enzo, Lord Bean, Vacca, Ghemon, Amir, Ape e Zampa, oltre al rapper statunitense Afu-Ra. Nel 2007 ha pubblicato l\u2019album Tilt insieme all\u2019MC milanese Blodi B, membro del collettivo Banhana Sapiens.<\/p><h6><strong>I Reset!<\/strong><\/h6><p>Nel 2008 Mace si avvicina alla musica elettronica e fonda i Reset! insieme a Alex Trecarichi, Rocco Civitelli, Vincenzo Catanzaro e Matteo Ievolella.[1] Le sonorit\u00e0 del gruppo sono state definite dalla critica specializzata come una fusione di funk, electro, house e hip hop.[2] Nel corso della loro attivit\u00e0 hanno pubblicato una serie di singoli ed EP attraverso etichette discografiche britanniche, australiane e giapponesi,[3] oltre ad aver realizzato remix ufficiali per Fatboy Slim, Cassius, Robyn, Bingo Players, Audio Bullys e Mad Decent (etichetta fondata da Diplo);<\/p><p>Durante la prima met\u00e0 degli anni duemiladieci il gruppo si \u00e8 esibito in Asia, Australia, Ibiza, Regno Unito e Giappone.[2][5][6]<\/p><p>Nel 2013 esce su Sony Music l\u2019album di esordio Future Madness che include la partecipazione di numerosi artisti come Erick Sermon degli EPMD, Keith Murray, Gu\u00e9 Pequeno, Emis Killa, Noyz Narcos, Clementino, Ensi, Ghemon, Francesco Sarcina e Paul King.[7] Il disco \u00e8 stato successivamente ristampato in Giappone con l\u2019aggiunta di vari remix.<\/p><p>\u00a0<\/p><h6><strong>Carriera solista<\/strong><\/h6><p>Mace in concerto a Milano, tappa dell\u2019OBE Live \u2013 An Out of Body Experience<br \/>Nel 2012 il musicista si avvicina al trap e a partire dal 2013 inizia a pubblicare i suoi primi singoli e EP da solista, prevalentemente su etichette statunitensi e britanniche, e a fare tour promozionali in Australia e Giappone. L\u2019anno successivo ritorna a produrre basi musicali per vari rapper italiani, tra cui Marracash, Gu\u00e9 Pequeno, Jake La Furia, Salmo, Noyz Narcos, Gemitaiz, MadMan, e Izi, per il quale realizza insieme a Shablo la base di Chic che viene certificato disco di platino.<\/p><p>Nel 2017 ha prodotto il singolo Pamplona di Fabri Fibra, in seguito certificato triplo disco di platino dalla FIMI e che ha conquistato la vetta della classifica airplay italiana. Tra il 2018 e il 2020 sono usciti i singoli Sindrome con Venerus, Immaginario con Colapesce, Non mi fido con Side Baby e gli Psicologi e Bianco\/Gospel con Gemitaiz.<\/p><p>Nel 2020 ha annunciato la firma con la Island Records e pubblicato contemporaneamente il singolo Ragazzi della nebbia, in cui sono presenti Irama e gli FSK Satellite: esso ha svolto il ruolo di singolo apripista del suo album di debutto. Intitolato OBE, il disco \u00e8 stato pubblicato il 5 febbraio 2021 e ha ottenuto un buon successo in Italia, debuttando in vetta alla Classifica FIMI Album; Il successo dell\u2019album \u00e8 stato reso possibile in special modo dal secondo singolo La canzone nostra (inciso con Blanco e Salmo), che ha dominato la Top Singoli per quattro settimane consecutive, venendo certificato disco d\u2019oro.<\/p><p>Dopo aver presentato il disco attraverso un evento trasmesso in streaming il 5 luglio 2021 presso l\u2019Arco Triofante della Galleria Vittorio Emanuele II di Milano, Mace ha annunciato la tourn\u00e9e OBE Live \u2013 An Out of Body Experience, composta da sei date e svoltasi nel maggio 2022, durante la quale \u00e8 stato accompagnato da vari musicisti.<\/p><p>Il 16 maggio 2022 ha annunciato l\u2019uscita del secondo album Oltre, avvenuto il 27 dello stesso mese. Contrariamente a OBE gli undici brani in esso contenuti sono del tutto strumentali e presenta sonorit\u00e0 che si alternano tra elettronica e psichedelica.<\/p><div>\u00a0<\/div><div><strong>MACE \u2013 12 Agosto 2022<\/strong><br \/><strong>Color Fest 10 \u2013 This Must Be The Place<\/strong><br \/><strong>Agriturismo Costantino<\/strong><\/div><p style=\"text-align: center;\"><span style=\"color: #ca5a8d;\"><a style=\"color: #ca5a8d;\" href=\"#podcast\"><strong>Ti sei perso il Color Fest ? ascolta qui il PODCAST!<\/strong><\/a><\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b624e59 elementor-widget elementor-widget-text-editor\" data-id=\"b624e59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000; letter-spacing: 0.35px;\">E tu sei curioso di ci\u00f2 che accade nel backstage di un festival?<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96b2421 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96b2421\" data-element_type=\"section\" data-e-type=\"section\" id=\"podcast\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c42b796\" data-id=\"c42b796\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcae0ea elementor-headline--style-rotate elementor-widget elementor-widget-animated-headline\" data-id=\"fcae0ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headline_style&quot;:&quot;rotate&quot;,&quot;animation_type&quot;:&quot;swirl&quot;,&quot;rotating_text&quot;:&quot;Spotify\\nApple Podcast\\nAmazon Music\\nGoogle Podcast\\nRSS&quot;,&quot;rotate_iteration_delay&quot;:1500,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h4 class=\"elementor-headline elementor-headline-animation-type-swirl elementor-headline-letters\">\r\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Ascoltaci pure su:<br><\/span>\r\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\r\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">\r\n\t\t\t\tSpotify\t\t\t<\/span>\r\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text\">\r\n\t\t\t\tApple&nbsp;Podcast\t\t\t<\/span>\r\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text\">\r\n\t\t\t\tAmazon&nbsp;Music\t\t\t<\/span>\r\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text\">\r\n\t\t\t\tGoogle&nbsp;Podcast\t\t\t<\/span>\r\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text\">\r\n\t\t\t\tRSS\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/h4>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5157151 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5157151\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-77dea24\" data-id=\"77dea24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfc9273 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cfc9273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/open.spotify.com\/show\/1mHfXompMrXV3AXEEyhhGp\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-spotify\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b2ed1fb\" data-id=\"b2ed1fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc8d6fa elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bc8d6fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/podcasts.apple.com\/us\/podcast\/color-fest-presenta-backstage-10-anni-di-festival\/id1656224733\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-podcast\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7c11793\" data-id=\"7c11793\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bd6d2e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0bd6d2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/music.amazon.it\/podcasts\/ce5f4f89-edff-4789-bec4-028f179f8de0\/color-fest-presenta-back-stage-10-anni-di-festival\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-amazon\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6ede602\" data-id=\"6ede602\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc90dc4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"dc90dc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/podcasts.google.com\/feed\/aHR0cHM6Ly9hbmNob3IuZm0vcy9jZDMwNDkwNC9wb2RjYXN0L3Jzcw\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-google\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c5234ef\" data-id=\"c5234ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47cc9ee elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"47cc9ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/anchor.fm\/s\/cd304904\/podcast\/rss\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-rss\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eddca09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eddca09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-05d2cd9\" data-id=\"05d2cd9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ef5bc6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0ef5bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/colorfest.it\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri la lineup 2023<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PODCAST Color Fest Backstage Di Color Fest Color Fest Backstage &#8211; 10 anni di Festival Nelle tre giornate del Color Fest abbiamo registrato un Podcast condotto da Vittorio Ondedei (Camillas) e Sara Di Iacovo, fatto di interviste e racconti della decima edizione con storie di #Backstage delle 9 edizioni precedenti e perch\u00e9 no di interviste [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":11382,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,168],"tags":[],"class_list":["post-11317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-color-fest","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Backstage Color Fest | 14 - 15 - 16 Agosto 2024<\/title>\n<meta name=\"description\" content=\"Nelle tre giornate di festival abbiamo registrato un Podcast condotto da Vittorio Ondedei (Camillas) e Sara Di Iacovo sui 10 anni Color Fest\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colorfest.it\/de\/backstage\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Color Fest Backstage\" \/>\n<meta property=\"og:description\" content=\"Color Fest - Festival di Musica, dal 2013 punto di riferimento per la musica dal vivo &gt;&gt; 11 - 12 - 13 Agosto 2026 Lungomare Falcone Borsellino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colorfest.it\/de\/backstage\/\" \/>\n<meta property=\"og:site_name\" content=\"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 | in Calabria\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/colorfestlamezia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-30T14:42:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T10:18:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/12\/copertina-agg2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salvatore Bilotti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salvatore Bilotti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"16\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/\"},\"author\":{\"name\":\"Salvatore Bilotti\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#\\\/schema\\\/person\\\/174195bbe9c056259e2ca3e13087d54b\"},\"headline\":\"Color Fest Backstage\",\"datePublished\":\"2022-12-30T14:42:01+00:00\",\"dateModified\":\"2024-01-19T10:18:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/\"},\"wordCount\":2879,\"publisher\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/copertina-agg2.jpg\",\"articleSection\":[\"Color Fest\",\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/\",\"url\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/\",\"name\":\"Backstage Color Fest | 14 - 15 - 16 Agosto 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/copertina-agg2.jpg\",\"datePublished\":\"2022-12-30T14:42:01+00:00\",\"dateModified\":\"2024-01-19T10:18:37+00:00\",\"description\":\"Nelle tre giornate di festival abbiamo registrato un Podcast condotto da Vittorio Ondedei (Camillas) e Sara Di Iacovo sui 10 anni Color Fest\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colorfest.it\\\/backstage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/copertina-agg2.jpg\",\"contentUrl\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/copertina-agg2.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"podcast Color Fest\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/backstage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/colorfest.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Color Fest Backstage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#website\",\"url\":\"https:\\\/\\\/colorfest.it\\\/\",\"name\":\"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 | in Calabria\",\"description\":\"Color Fest - Festival di Musica, dal 2013 punto di riferimento per la musica dal vivo &gt;&gt; 11 - 12 - 13 Agosto 2026 Lungomare Falcone Borsellino.\",\"publisher\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/#organization\"},\"alternateName\":\"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 @Lungomare Falcone Borsellino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colorfest.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#organization\",\"name\":\"Che cosa sono le nuvole APS\",\"alternateName\":\"Color Fest\",\"url\":\"https:\\\/\\\/colorfest.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/checosasonolenuvole.png\",\"contentUrl\":\"https:\\\/\\\/colorfest.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/checosasonolenuvole.png\",\"width\":952,\"height\":844,\"caption\":\"Che cosa sono le nuvole APS\"},\"image\":{\"@id\":\"https:\\\/\\\/colorfest.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/colorfestlamezia\\\/\",\"http:\\\/\\\/instagram.com\\\/color_fest_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/color-fest\\\/\"],\"description\":\"Color Fest - Festival di Musica, dal 2013 punto di riferimento per la musica dal vivo >> 11 - 12 - 13 Agosto 2026 Lungomare Falcone Borsellino.\",\"email\":\"scrivi@colorfest.it\",\"legalName\":\"Che cosa sono le nuvole APS\",\"foundingDate\":\"2012-10-12\",\"vatID\":\"03309120792\",\"taxID\":\"92029190797\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colorfest.it\\\/#\\\/schema\\\/person\\\/174195bbe9c056259e2ca3e13087d54b\",\"name\":\"Salvatore Bilotti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g\",\"caption\":\"Salvatore Bilotti\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Backstage Color Fest | 14. \u2013 15. \u2013 16. August 2024","description":"W\u00e4hrend der drei Festivaltage haben wir einen Podcast mit Vittorio Ondedei (Camillas) und Sara Di Iacovo \u00fcber die 10 Jahre Color Fest aufgenommen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colorfest.it\/de\/backstage\/","og_locale":"de_DE","og_type":"article","og_title":"Color Fest Backstage","og_description":"Color Fest - Festival di Musica, dal 2013 punto di riferimento per la musica dal vivo >> 11 - 12 - 13 Agosto 2026 Lungomare Falcone Borsellino.","og_url":"https:\/\/colorfest.it\/de\/backstage\/","og_site_name":"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 | in Calabria","article_publisher":"http:\/\/facebook.com\/colorfestlamezia\/","article_published_time":"2022-12-30T14:42:01+00:00","article_modified_time":"2024-01-19T10:18:37+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/12\/copertina-agg2.jpg","type":"image\/jpeg"}],"author":"Salvatore Bilotti","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Salvatore Bilotti","Gesch\u00e4tzte Lesezeit":"16\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/colorfest.it\/backstage\/#article","isPartOf":{"@id":"https:\/\/colorfest.it\/backstage\/"},"author":{"name":"Salvatore Bilotti","@id":"https:\/\/colorfest.it\/#\/schema\/person\/174195bbe9c056259e2ca3e13087d54b"},"headline":"Color Fest Backstage","datePublished":"2022-12-30T14:42:01+00:00","dateModified":"2024-01-19T10:18:37+00:00","mainEntityOfPage":{"@id":"https:\/\/colorfest.it\/backstage\/"},"wordCount":2879,"publisher":{"@id":"https:\/\/colorfest.it\/#organization"},"image":{"@id":"https:\/\/colorfest.it\/backstage\/#primaryimage"},"thumbnailUrl":"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/12\/copertina-agg2.jpg","articleSection":["Color Fest","News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/colorfest.it\/backstage\/","url":"https:\/\/colorfest.it\/backstage\/","name":"Backstage Color Fest | 14. \u2013 15. \u2013 16. August 2024","isPartOf":{"@id":"https:\/\/colorfest.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colorfest.it\/backstage\/#primaryimage"},"image":{"@id":"https:\/\/colorfest.it\/backstage\/#primaryimage"},"thumbnailUrl":"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/12\/copertina-agg2.jpg","datePublished":"2022-12-30T14:42:01+00:00","dateModified":"2024-01-19T10:18:37+00:00","description":"W\u00e4hrend der drei Festivaltage haben wir einen Podcast mit Vittorio Ondedei (Camillas) und Sara Di Iacovo \u00fcber die 10 Jahre Color Fest aufgenommen.","breadcrumb":{"@id":"https:\/\/colorfest.it\/backstage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colorfest.it\/backstage\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colorfest.it\/backstage\/#primaryimage","url":"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/12\/copertina-agg2.jpg","contentUrl":"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/12\/copertina-agg2.jpg","width":1000,"height":1000,"caption":"podcast Color Fest"},{"@type":"BreadcrumbList","@id":"https:\/\/colorfest.it\/backstage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/colorfest.it\/"},{"@type":"ListItem","position":2,"name":"Color Fest Backstage"}]},{"@type":"WebSite","@id":"https:\/\/colorfest.it\/#website","url":"https:\/\/colorfest.it\/","name":"Color Fest - Musikfestival | 11 - 12 - 13 August 2026 | in Kalabrien","description":"Color Fest - Musikfestival, seit 2013 ein Bezugspunkt f\u00fcr Live-Musik &gt;&gt; 11 - 12 - 13 August 2026 Lungomare Falcone Borsellino","publisher":{"@id":"https:\/\/colorfest.it\/#organization"},"alternateName":"Color Fest - Festival di Musica | 11 - 12 - 13 Agosto 2026 @Lungomare Falcone Borsellino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colorfest.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/colorfest.it\/#organization","name":"Was sind APS-Wolken?","alternateName":"Color Fest","url":"https:\/\/colorfest.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colorfest.it\/#\/schema\/logo\/image\/","url":"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/03\/checosasonolenuvole.png","contentUrl":"https:\/\/colorfest.it\/wp-content\/uploads\/2022\/03\/checosasonolenuvole.png","width":952,"height":844,"caption":"Che cosa sono le nuvole APS"},"image":{"@id":"https:\/\/colorfest.it\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/colorfestlamezia\/","http:\/\/instagram.com\/color_fest_\/","https:\/\/www.linkedin.com\/company\/color-fest\/"],"description":"Color Fest - Musikfestival, seit 2013 ein Bezugspunkt f\u00fcr Live-Musik &gt;&gt; 11 - 12 - 13 August 2026 Lungomare Falcone Borsellino","email":"scrivi@colorfest.it","legalName":"Che cosa sono le nuvole APS","foundingDate":"2012-10-12","vatID":"03309120792","taxID":"92029190797","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/colorfest.it\/#\/schema\/person\/174195bbe9c056259e2ca3e13087d54b","name":"Salvatore Bilotti","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ffea54082f2805c177a23aec9bc4121df09c213e6ca8fda40be720241c65e38e?s=96&d=mm&r=g","caption":"Salvatore Bilotti"}}]}},"_links":{"self":[{"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/posts\/11317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/comments?post=11317"}],"version-history":[{"count":0,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/posts\/11317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/media\/11382"}],"wp:attachment":[{"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/media?parent=11317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/categories?post=11317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colorfest.it\/de\/wp-json\/wp\/v2\/tags?post=11317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}